{"id":14617,"date":"2021-02-18T19:21:58","date_gmt":"2021-02-18T18:21:58","guid":{"rendered":"https:\/\/anihabara.de\/index.php\/2021\/02\/18\/belle-studio-chizu-zeigt-ersten-teaser-zum-neuen-film-von-mamoru-hosoda-2\/"},"modified":"2023-11-28T01:04:13","modified_gmt":"2023-11-28T00:04:13","slug":"belle-studio-chizu-zeigt-ersten-teaser-zum-neuen-film-von-mamoru-hosoda-2","status":"publish","type":"post","link":"https:\/\/anihabara.de\/index.php\/2021\/02\/18\/belle-studio-chizu-zeigt-ersten-teaser-zum-neuen-film-von-mamoru-hosoda-2\/","title":{"rendered":"\u00bbBelle\u00ab &#8211; Studio Chizu zeigt ersten Teaser zum neuen Film von Mamoru Hosoda"},"content":{"rendered":"<p><span style=\"font-size: 16pt;\">Die Storyboards sind fertig, die Produktion macht Fortschritte: Wer \u00bbSummer Wars\u00ab mochte, wird mit \u00bbBelle\u00ab seinen Spa\u00df haben, verspricht das Studio.<\/span><\/p>\n<p><!--more--><\/p>\n<p>Studio Chizu ver\u00f6ffentlichte am Donnerstag \u00fcber seine Kan\u00e4le einen ersten Teaser-Trailer sowie ein Visual zum neusten Animefilm \u00bbBelle\u00ab \u2013 im Original \u00bbRy\u016b to Sobakasu no Hime\u00ab etwa \u00bbDie Prinzessin von Drachen und Sommersprossen\u00ab \u2013 von Studiogr\u00fcnder Mamoru Hosoda. Der 53-J\u00e4hrige f\u00fchrt dabei die Regie, schreibt das Drehbuch und entwarf die urspr\u00fcngliche Idee. Der Film soll im Sommer 2021 in den japanischen Kinos gezeigt werden und markiert das zehnj\u00e4hrige Jubil\u00e4um des Animestudios. Zuletzt lies Hosoda bereits im Rahmen einer Pressekonferenz f\u00fcr das \u00bbTokyo Anime Award Festival 2021\u00ab Ende Oktober durchblicken, dass er die Storyboards f\u00fcr ein neues Filmprojekt k\u00fcrzlich fertiggestellt habe und die Produktion nun richtig beginne.<\/p>\n<p><iframe src=\"https:\/\/www.youtube.com\/embed\/0MSkH5AU__8\" width=\"480\" height=\"270\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><br \/>\n\u00bbBelle\u00ab spielt in einer sich endlos weiterentwickelnden Online-Welt namens U mit \u00fcber 5 Milliarden registrierten Benutzern. Genau wie Hosodas fr\u00fchere Werke, die virtuelle Welten thematisierten, wie \u00bbDigimon: Der Film\u00ab und \u00bbSummer Wars\u00ab besch\u00e4ftigt er sich mit den Strukturen der modernen Gesellschaft, aber basierend auf neuen Beobachtungen des Regisseurs. Die Ank\u00fcndigung nennt au\u00dferdem Coming of Age, Familienbindungen, Liebe zwischen Eltern und Kindern, Freundschaft \u00fcber Speziesgrenzen hinaus sowie die Verbindung zwischen unseren Leben explizit als Themen des Films \u2013 eine Anspielung auf alle bisherigen Filme Hosodas.<\/p>\n<p><img decoding=\"async\" style=\"float: right; margin-left: 2%;\" src=\"images\/stories\/belle.jpg\" alt=\"\" width=\"25%\" \/>Mamoru Hosoda feierte sein Regiedeb\u00fct 2000 bei Toei Animation mit \u00bbDigimon: Der Film\u00ab. Im Jahr 2005 wechselte er zu Madhouse, wo er \u00bbDas M\u00e4dchen, das durch die Zeit sprang\u00ab (2006) sowie \u00bbSummer Wars\u00ab (2009) produzierte \u2013 beide Filme gewannen im darauffolgenden Jahr den \u00bbJapanese Academy Award\u00ab in der Kategorie \u00bbBester Animationsfilm\u00ab. Zusammen mit Produzent Yuichiro Saito (\u00bbDas M\u00e4dchen, das durch die Zeit sprang\u00ab, \u00bbSummer Wars\u00ab) gr\u00fcndete Hosoda 2011 Studio Chizu, wo \u00bbAme &amp; Yuki: Die Wolfskinder\u00ab (2012), \u00bbDer Junge &amp; das Biest\u00ab (2015) sowie \u00bbMirai\u00ab (2018) entstanden. \u00bbMirai\u00ab wurde ferner 2019 f\u00fcr den Oscar in der Kategorie \u00bbBester Animationsfilm\u00ab nominiert. Seit der Erstverleihung der Kategorie im Jahr 2002 nominierte die Academy lediglich sieben japanische Animationsfilme.\u00a0Kaz\u00e9 Anime und Leonine Anime ver\u00f6ffentlichten seine Filme auf DVD und Blu-ray.<\/p>\n<p><span style=\"text-decoration: underline;\">Darum geht es:<\/span><\/p>\n<blockquote><p>Die 17-j\u00e4hrige Obersch\u00fclerin Suzu verlor im jungen Alter ihre Mutter durch einen Unfall und lebt seitdem mit ihrem Vater in einer eher l\u00e4ndlichen Gegend. Dort kommt Suzu das erste Mal mit \u00bbU\u00ab in Kontakt \u2013 einer virtuellen Welt. Bald schon meldet sie sich als Belle bei dem Dienst an und erregt mit ihrem Gesang weltweite Aufmerksamkeit. Zu allem \u00dcberfluss trifft sie mit ihrem Avatar dann auch auf eine mysteri\u00f6se Kreatur in der Gestalt eines Drachen.<\/p>\n<p><small>eigene \u00dcbersetzung<\/small><\/p><\/blockquote>\n<p>(Quelle: ANN)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Storyboards sind fertig, die Produktion macht Fortschritte: Wer \u00bbSummer Wars\u00ab mochte, wird mit \u00bbBelle\u00ab seinen Spa\u00df haben, verspricht das Studio.<\/p>\n","protected":false},"author":100,"featured_media":17457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[983],"tags":[1016,1023],"class_list":["post-14617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-anime-jp","tag-neuer-animefilm","tag-originalwerk"],"acf":[],"_links":{"self":[{"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/posts\/14617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/comments?post=14617"}],"version-history":[{"count":2,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/posts\/14617\/revisions"}],"predecessor-version":[{"id":21394,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/posts\/14617\/revisions\/21394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/media\/17457"}],"wp:attachment":[{"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/media?parent=14617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/categories?post=14617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/tags?post=14617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}