{"id":12889,"date":"2018-02-14T16:09:40","date_gmt":"2018-02-14T15:09:40","guid":{"rendered":"https:\/\/anihabara.de\/index.php\/2018\/02\/14\/altraverse-weitere-manga-fuer-kommendes-jahr-angekuendigt\/"},"modified":"2023-12-17T01:02:49","modified_gmt":"2023-12-17T00:02:49","slug":"altraverse-weitere-manga-fuer-kommendes-jahr-angekuendigt","status":"publish","type":"post","link":"https:\/\/anihabara.de\/index.php\/2018\/02\/14\/altraverse-weitere-manga-fuer-kommendes-jahr-angekuendigt\/","title":{"rendered":"Altraverse &#8211; Weitere Manga f\u00fcr kommendes Jahr angek\u00fcndigt"},"content":{"rendered":"<p><span style=\"font-size: 16pt;\">\u00bbKakegurui\u00ab, \u00bbMade in Abyss\u00ab, \u00bbGoblin Slayer!\u00ab: Nach den ersten Titeln im Dezember hat Altraverse nachgelegt. Nun steht das Programm.<\/span><\/p>\n<p><!--more--><\/p>\n<p>Neben \u00bbBis meine Knochen verrotten\u00ab, \u00bbKeine Cheats f\u00fcr die Liebe\u00ab, \u00bbInterviews mit Monster-M\u00e4dchen\u00ab und \u00bbGame \u2013 Lust ohne Liebe\u00ab (<a href=\"https:\/\/anihabara.de\/index.php\/2017\/12\/26\/altraverse-das-sind-die-ersten-titel-des-neuen-manga-verlages\/\" target=\"_blank\" rel=\"noopener\">wir berichteten<\/a>) sicherte sich der neue Manga-Verlag Altraverse f\u00fcr sein erstes Programm zw\u00f6lf weitere Titel, die zwischen April und Juli den Weg in den Handel finden \u2013 darunter auch eine Lightnovel.<\/p>\n<p><span style=\"font-size: 16pt;\">Kakegurui \u2013 Das Leben ist ein Spiel<br \/>\n<\/span><\/p>\n<hr style=\"margin-top: 10px;\" \/>\n<p><img decoding=\"async\" style=\"width: 25%; float: right; margin-left: 2%;\" src=\"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/12\/142175l.jpg\" alt=\"Kakegurui \u2013 Das Leben ist ein Spiel\" border=\"0\" \/>Gambling als Schulfach: Ab Mai 2018 erscheint \u00bbKakegurui \u2013 Das Leben ist ein Spiel\u00ab von Autorin Homura Kawamoto und Zeichner T\u014dru Naomura in deutscher Sprache. Die Manga-Reihe wird seit M\u00e4rz 2014 im \u00bbGangan Joker\u00ab abgedruckt und z\u00e4hlt bisher 9 B\u00e4nde in Japan. Bei uns erscheint das Psychodrama im Taschenbuchformat (12,8 x 18,5 cm) zu einem Preis von jeweils 7 Euro. Ab Juli 2017 wurde ferner im japanischen Fernsehen au\u00dferdem eine gleichnamige Anime-Umsetzung von Studio Mappa gezeigt. Im Februar erschien die Serie mit deutscher Sprachausgabe bei Netflix.<\/p>\n<p><span style=\"text-decoration: underline;\">Darum geht es:<\/span><\/p>\n<blockquote><p>An der Hyakko-Privatschule beurteilen sich die Sch\u00fcler nicht nach ihrem K\u00f6nnen im Unterricht oder Sport, denn diese F\u00e4higkeiten sind belanglos f\u00fcr Menschen, die zum Regieren geboren sind. Taktisches Verst\u00e4ndnis, Scharfsinn und Willenskraft sind gefragt und was eignet sich besser, um diese zu messen, als ein Stundenplan voller verr\u00fcckter Gl\u00fccksspiele? Yumeko ist neu an der Hyakko-Privatschule und legt sich ohne R\u00fccksicht auf Verluste mit all ihren Mitsch\u00fclern an. Selbst vor den Mitgliedern des ber\u00fcchtigten Schulrats, der das Gl\u00fcckspiel an der Schule kontrolliert, macht sie keinen Halt.<\/p>\n<p><small>Altraverse<\/small><\/p><\/blockquote>\n<p><span style=\"font-size: 16pt;\">Made in Abyss<br \/>\n<\/span><\/p>\n<hr style=\"margin-top: 10px;\" \/>\n<p><img decoding=\"async\" style=\"width: 25%; float: right; margin-left: 2%;\" src=\"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/12\/161645l.jpg\" alt=\"Made in Abyss\" border=\"0\" \/>Verlust, Gewalt, Entt\u00e4uschung, aber auch Hoffnung, Vertrauen und Liebe: Mit \u00bbMade in Abyss\u00ab erscheint ab Juni 2018 die Abenteuer-Geschichte von Akihito Tsukushi bei Altraverse, die der 38-J\u00e4hrige seit Oktober 2012 f\u00fcr das \u00bbWeb Comic Gamma\u00ab zeichnet. Verlag Takeshobo ver\u00f6ffentlichte in Japan bisher 6 B\u00e4nde des Geheimtipps. Hierzulande erscheint die Reihe dann im Gro\u00dfformat (14,8 x 21 cm) zu einem Preis von jeweils 10 Euro. Die gleichnamige Anime-Umsetzung von Kinema Citrus feierte im Sommer 2017 seine Premiere und wurde vor Kurzem von Universum Anime lizenziert \u2013 wir <a href=\"https:\/\/anihabara.de\/index.php\/2018\/02\/15\/universum-anime-lizenziert-made-in-abyss-grimoire-of-zero\/\">berichteten<\/a>.<\/p>\n<p><span style=\"text-decoration: underline;\">Darum geht es:<\/span><\/p>\n<blockquote><p>Das riesige H\u00f6hlensystem Abyss ist der letzte unerforschte Ort der Welt. Ganze Generationen von mutigen Abenteurern, bekannt als H\u00f6hlentaucher, haben ihr Leben der Erkundung dieses mystischen und von gef\u00e4hrlichen Monstern bewohnten Systems verschrieben. In einer Stadt am Rande des Abyss lebt die junge Weise Rico, die davon tr\u00e4umt eine genauso ber\u00fchmte H\u00f6hlentaucherin, wie ihre Mutter zu werden. Auf einer kurzen Erkundungstour der h\u00f6heren Eben des Abyss, trifft sie auf einen kleinen Jungen, der sich als Roboter entpuppt. Sie rettet ihn und gibt ihm den Namen Reg. Zusammen entscheiden sich die beiden, die Tiefen der H\u00f6hlen zu erkunden und nicht nur das R\u00e4tsel um Regs Ursprung, sondern auch um das Verschwinden von Ricos Mutter zu l\u00fcften.<\/p>\n<p><small>Altraverse<\/small><\/p><\/blockquote>\n<p><span style=\"font-size: 16pt;\">Goblin Slayer!<br \/>\n<\/span><\/p>\n<hr style=\"margin-top: 10px;\" \/>\n<p><img decoding=\"async\" style=\"width: 25%; float: right; margin-left: 2%;\" src=\"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/12\/183163l.jpg\" alt=\"Goblin Slayer!\" border=\"0\" \/>Fans von Dark-Fantasy-Settings aufgepasst: \u00bbGoblin Slayer!\u00ab von Autor Kumo Kagyu und Zeichner Kousuke Kurose startet ab Juli 2018 bei Altraverse. In Japan erschien der Seinen-Manga seit Mai 2016 im Magazin \u00bbBig Gangan\u00ab von Square Enix und umspannt aktuell 3 B\u00e4nde. Zugrunde liegt die gleichnamige Lightnovel des Autors, woran er und Illustrator Noboru Kannatsuki seit Februar 2016 arbeiten. Bei uns erscheint die Reihe im Taschenbuchformat (12,8 x 18,5 cm) zu einem Preis von jeweils 7 Euro.<\/p>\n<p><span style=\"text-decoration: underline;\">Darum geht es:<\/span><\/p>\n<blockquote><p>Eine junge Priesterin schlie\u00dft sich ihrer ersten Abenteurergruppe an, nur um sich kurz darauf in Lebensgefahr zu befinden. Sie und ihre Kameraden sind von Goblins in eine H\u00f6hle gelockt und \u00fcberw\u00e4ltigt worden. Zu ihrem Gl\u00fcck hat sich der Goblin Slayer, ein Mann, der sein ganzes Leben dem T\u00f6ten von Goblins gewidmet hat, genau diese H\u00f6hle als sein Jagdrevier f\u00fcr diesen Tag ausgesucht. Dankbar f\u00fcr ihre Rettung entscheidet die junge Priesterin sich dem Goblin Slayer anzuschlie\u00dfen und ihn in einem h\u00e4rtesten Jobs der Abenteurerwelt zu unterst\u00fctzen: Dem Ausl\u00f6schen von Goblins.<\/p>\n<p><small>Altraverse<\/small><\/p><\/blockquote>\n<p><span style=\"text-decoration: underline;\">Weitere Titel:<\/span><\/p>\n<table>\n<tbody>\n<tr>\n<td style=\"width: 24%;\" valign=\"top\"><img decoding=\"async\" src=\"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/12\/191957l.jpg\" alt=\"Record of Grancrest War\" border=\"0\" \/><\/td>\n<td style=\"width: 24%;\" valign=\"top\"><img decoding=\"async\" src=\"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/12\/198694l.jpg\" alt=\"Granblue Fantasy\" border=\"0\" \/><\/td>\n<td style=\"width: 24%;\" valign=\"top\"><img decoding=\"async\" src=\"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/12\/54e674b7a6a9e_187488b.jpg\" alt=\"In these words\" border=\"0\" \/><\/td>\n<td style=\"width: 24%;\" valign=\"top\"><img decoding=\"async\" src=\"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/12\/205425l.jpg\" alt=\"Sister &amp; Vampire\" border=\"0\" \/><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\"><strong>Record of Grancrest War<\/strong><\/p>\n<ul>\n<li>Mangaka: Ryou Mizuno (Autor), Miyuu (Illustrator)<\/li>\n<li>Genre: Abenteuer, Actiondrama, Fantasy<\/li>\n<li>Ver\u00f6ffentlichung: Juni 2016 bis ?<\/li>\n<li>bisher 2 B\u00e4nde<\/li>\n<li>Start: ab April 2018 (7\u20ac pro Band)<\/li>\n<\/ul>\n<\/td>\n<td valign=\"top\"><strong>Granblue Fantasy<\/strong><\/p>\n<ul>\n<li>Mangaka: Kenji Ooiwa<\/li>\n<li>Genre: Abenteuer, Action, Fantasyk<\/li>\n<li>Ver\u00f6ffentlichung: Mai 2017 bis ?<\/li>\n<li>bisher 3 B\u00e4nde<\/li>\n<li>Start: ab Mai 2018 (7\u20ac pro Band)<\/li>\n<\/ul>\n<\/td>\n<td valign=\"top\"><strong>In these words<\/strong><\/p>\n<ul>\n<li>Mangaka: Kichiku Neko (Autor), Jun Togai (Illustrator)<\/li>\n<li>Genre: Psychodrama, Krimi, Yaoi<\/li>\n<li>Ver\u00f6ffentlichung: September 2012 bis ?<\/li>\n<li>bisher 3 B\u00e4nde<\/li>\n<li>Start: ab Mai 2018 (10\u20ac pro Band)<\/li>\n<\/ul>\n<\/td>\n<td valign=\"top\"><strong>Sister &amp; Vampire<\/strong><\/p>\n<ul>\n<li>Mangaka: Akatsuki<\/li>\n<li>Genre: Fantasy, Vampire, Erotik<\/li>\n<li>Ver\u00f6ffentlichung: Oktober 2015 bis ?<\/li>\n<li>bisher 3 B\u00e4nde<\/li>\n<li>Start: ab Mai 2018 (7\u20ac pro Band)<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 24%;\" valign=\"top\"><img decoding=\"async\" src=\"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/12\/51Z71rjkfYL._SX313_BO1204203200_.jpg\" alt=\"Daydream Lover\" border=\"0\" \/><\/td>\n<td style=\"width: 24%;\" valign=\"top\"><img decoding=\"async\" src=\"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/12\/126627l.jpg\" alt=\"Kein Dad wie jeder andere\" border=\"0\" \/><\/td>\n<td style=\"width: 24%;\" valign=\"top\"><img decoding=\"async\" src=\"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/12\/549cfc8c08ed4_187488b.jpg\" alt=\"Maybe someday (Lightnovel)\" border=\"0\" \/><\/td>\n<td style=\"width: 24%;\" valign=\"top\"><img decoding=\"async\" src=\"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/12\/125235l.jpg\" alt=\"Lip Smoke \u2013 Gl\u00fchende Lippen\" border=\"0\" \/><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\"><strong>Daydream Lover<\/strong><\/p>\n<ul>\n<li>Mangaka: Yukino Seo<\/li>\n<li>Genre: romantische Kom\u00f6die, Erotik<\/li>\n<li>Ver\u00f6ffentlichung: Juli 2015 bis Oktober 2017<\/li>\n<li>in 2 B\u00e4nden abgeschlossen<\/li>\n<li>Start: ab Juni 2018 (7\u20ac pro Band)<\/li>\n<\/ul>\n<\/td>\n<td valign=\"top\"><strong>Kein Dad wie jeder andere<\/strong><\/p>\n<ul>\n<li>Mangaka: Choujin<\/li>\n<li>Genre: Liebesdrama, Slice of Life<\/li>\n<li>Ver\u00f6ffentlichung: 2013 bis ?<\/li>\n<li>bisher 7 B\u00e4nde<\/li>\n<li>Start: ab Juni 2018 (7\u20ac pro Band)<\/li>\n<\/ul>\n<\/td>\n<td valign=\"top\"><strong>Maybe someday (Lightnovel)<\/strong><\/p>\n<ul>\n<li>Mangaka: Kichiku Neko (Autor), TogaQ (Illustrator)<\/li>\n<li>Genre: Psychodrama, Krimi, Yaoi<\/li>\n<li>Ver\u00f6ffentlichung: 2015<\/li>\n<li>Einzelband<\/li>\n<li>Start: im Juli 2018 (10\u20ac)<\/li>\n<\/ul>\n<\/td>\n<td valign=\"top\"><strong>Lip Smoke \u2013 Gl\u00fchende Lippen<\/strong><\/p>\n<ul>\n<li>Mangaka: Mai Nishikata<\/li>\n<li>Genre: Romanze<\/li>\n<li>Ver\u00f6ffentlichung: April 2013 bis Januar 2014<\/li>\n<li>Einzelband<\/li>\n<li>Start: im Juli 2018 (7\u20ac)<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 24%;\" valign=\"top\"><img decoding=\"async\" src=\"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/12\/34151l.jpg\" alt=\"Super Lovers\" border=\"0\" \/><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\"><strong>Super Lovers<\/strong><\/p>\n<ul>\n<li>Mangaka: Miyuki Abe<\/li>\n<li>Genre: Drama, Kom\u00f6die, Yaoi<\/li>\n<li>Ver\u00f6ffentlichung: Dezember 2009 bis ?<\/li>\n<li>bisher 11 B\u00e4nde<\/li>\n<li>Start: ab Juli 2018<\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>(Quelle: Altraverse)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bbKakegurui\u00ab, \u00bbMade in Abyss\u00ab, \u00bbGoblin Slayer!\u00ab: Nach den ersten Titeln im Dezember hat Altraverse nachgelegt. Nun steht das Programm.<\/p>\n","protected":false},"author":100,"featured_media":18758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"episode_type":"","audio_file":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","date_recorded":"","explicit":"","block":"","filesize_raw":"","footnotes":""},"categories":[995],"tags":[1046],"class_list":["post-12889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-manga-de","tag-mangalizenz"],"acf":[],"_links":{"self":[{"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/posts\/12889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/comments?post=12889"}],"version-history":[{"count":4,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/posts\/12889\/revisions"}],"predecessor-version":[{"id":24041,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/posts\/12889\/revisions\/24041"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/media\/18758"}],"wp:attachment":[{"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/media?parent=12889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/categories?post=12889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/tags?post=12889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}