{"id":19951,"date":"2019-09-15T19:00:30","date_gmt":"2019-09-15T17:00:30","guid":{"rendered":"https:\/\/anihabara.de\/?post_type=podcast&#038;p=19951"},"modified":"2024-01-19T21:08:35","modified_gmt":"2024-01-19T20:08:35","slug":"folge-15-bite-za-dusto-ii","status":"publish","type":"podcast","link":"https:\/\/anihabara.de\/index.php\/podcast\/folge-15-bite-za-dusto-ii\/","title":{"rendered":"Folge 15 &#8211; BITE ZA DUSTO II"},"content":{"rendered":"<p>Immer noch gefangen im Strudel der Zeit diskutieren Lukas und Julian Serien, die es hoffentlich in einer reparierten Zeitlinie nach Deutschland schaffen. Dabei geht es um pubert\u00e4re Probleme durch K\u00f6rpertausch, um halsbrecherische Abfahrten zu geilen Beats und zwei Serien, deren kompletter Character-Cast nicht einmal in ein Telefonbuch passen w\u00fcrde. Der Abschluss des Murmeltier-Arcs steht kurz bevor!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Immer noch gefangen im Strudel der Zeit diskutieren Lukas und Julian Serien, die es hoffentlich in einer reparierten Zeitlinie nach Deutschland schaffen. Dabei geht es um pubert\u00e4re Probleme durch K\u00f6rpertausch, um halsbrecherische Abfahrten zu geilen Beats und zwei Serien, deren kompletter Character-Cast nicht einmal in ein Telefonbuch passen w\u00fcrde. Der Abschluss des Murmeltier-Arcs steht kurz bevor!<\/p>\n","protected":false},"author":1,"featured_media":19448,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"episode_type":"audio","audio_file":"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/11\/podcast_8932_antenne_akihabara_episode_16_folge_15_bite_za_dusto_ii.mp3","cover_image":"","cover_image_id":"","duration":"47:50","filesize":"38.86M","date_recorded":"2019-09-15 19:00:30","explicit":"","block":"","filesize_raw":"40745420"},"tags":[1141,1142],"series":[37],"class_list":["post-19951","podcast","type-podcast","status-publish","has-post-thumbnail","hentry","tag-lukeohl","tag-tedz","series-antenne-akihabara"],"acf":[],"episode_featured_image":"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/10\/766c1718-99e4-4ca4-babd-201462f186f4.png","episode_player_image":"https:\/\/anihabara.de\/wp-content\/uploads\/2023\/10\/766c1718-99e4-4ca4-babd-201462f186f4.png","download_link":"https:\/\/anihabara.de\/podcast-download\/19951\/folge-15-bite-za-dusto-ii.mp3","player_link":"https:\/\/anihabara.de\/podcast-player\/19951\/folge-15-bite-za-dusto-ii.mp3","audio_player":null,"episode_data":{"playerMode":"dark","subscribeUrls":{"apple_podcasts":{"key":"apple_podcasts","url":"https:\/\/podcasts.apple.com\/de\/podcast\/antenne-akihabara-ein-deutscher-anime-plausch\/id1452368626","label":"Apple Podcasts","class":"apple_podcasts","icon":"apple-podcasts.png"},"stitcher":{"key":"stitcher","url":"","label":"Stitcher","class":"stitcher","icon":"stitcher.png"},"google_podcasts":{"key":"google_podcasts","url":"https:\/\/podcasts.google.com\/feed\/aHR0cHM6Ly9hbnRlbm5lYWtpYmEucG9kaWdlZS5pby9mZWVkL21wMw","label":"Google Podcasts","class":"google_podcasts","icon":"google-podcasts.png"},"spotify":{"key":"spotify","url":"https:\/\/open.spotify.com\/show\/1bLpx03PjzelkjcPnOnyNy","label":"Spotify","class":"spotify","icon":"spotify.png"}},"rssFeedUrl":"https:\/\/anihabara.de\/feed\/podcast\/antenne-akihabara","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"2XI9cxqyKf\"><a href=\"https:\/\/anihabara.de\/index.php\/podcast\/folge-15-bite-za-dusto-ii\/\">Folge 15 &#8211; BITE ZA DUSTO II<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"https:\/\/anihabara.de\/index.php\/podcast\/folge-15-bite-za-dusto-ii\/embed\/#?secret=2XI9cxqyKf\" width=\"500\" height=\"350\" title=\"&#8222;Folge 15 &#8211; BITE ZA DUSTO II&#8220; &#8211; Anihabara.de\" data-secret=\"2XI9cxqyKf\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n\/\/# sourceURL=https:\/\/anihabara.de\/wp-includes\/js\/wp-embed.min.js\n\/* ]]> *\/\n<\/script>\n"},"_links":{"self":[{"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/podcast\/19951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/comments?post=19951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/media\/19448"}],"wp:attachment":[{"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/media?parent=19951"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/tags?post=19951"},{"taxonomy":"series","embeddable":true,"href":"https:\/\/anihabara.de\/index.php\/wp-json\/wp\/v2\/series?post=19951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}